{"id":4148,"count":1,"description":"","link":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/","name":"304 sensitive places have been identified in terms of flood and water logging","slug":"304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>304 sensitive places have been identified in terms of flood and water logging Archives - Himalaya Ki Awaj<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"304 sensitive places have been identified in terms of flood and water logging Archives - Himalaya Ki Awaj\" \/>\n<meta property=\"og:url\" content=\"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/\" \/>\n<meta property=\"og:site_name\" content=\"Himalaya Ki Awaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/\",\"url\":\"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/\",\"name\":\"304 sensitive places have been identified in terms of flood and water logging Archives - Himalaya Ki Awaj\",\"isPartOf\":{\"@id\":\"https:\/\/himalayakiawaj.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/himalayakiawaj.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"304 sensitive places have been identified in terms of flood and water logging\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/himalayakiawaj.com\/#website\",\"url\":\"https:\/\/himalayakiawaj.com\/\",\"name\":\"Himalaya Ki Awaj\",\"description\":\"News\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/himalayakiawaj.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"304 sensitive places have been identified in terms of flood and water logging Archives - Himalaya Ki Awaj","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/","og_locale":"en_US","og_type":"article","og_title":"304 sensitive places have been identified in terms of flood and water logging Archives - Himalaya Ki Awaj","og_url":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/","og_site_name":"Himalaya Ki Awaj","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/","url":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/","name":"304 sensitive places have been identified in terms of flood and water logging Archives - Himalaya Ki Awaj","isPartOf":{"@id":"https:\/\/himalayakiawaj.com\/#website"},"breadcrumb":{"@id":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/himalayakiawaj.com\/index.php\/tag\/304-sensitive-places-have-been-identified-in-terms-of-flood-and-water-logging\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/himalayakiawaj.com\/"},{"@type":"ListItem","position":2,"name":"304 sensitive places have been identified in terms of flood and water logging"}]},{"@type":"WebSite","@id":"https:\/\/himalayakiawaj.com\/#website","url":"https:\/\/himalayakiawaj.com\/","name":"Himalaya Ki Awaj","description":"News","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/himalayakiawaj.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/himalayakiawaj.com\/index.php\/wp-json\/wp\/v2\/tags\/4148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/himalayakiawaj.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/himalayakiawaj.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/himalayakiawaj.com\/index.php\/wp-json\/wp\/v2\/posts?tags=4148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}